{"id":382212,"date":"2023-06-22T10:47:21","date_gmt":"2025-01-21T15:44:54","guid":{"rendered":"https:\/\/mediatrade.fi\/tuote\/mka-system-pole-xs-13cm-aluminum-2\/"},"modified":"2026-01-23T12:24:12","modified_gmt":"2026-01-23T10:24:12","slug":"mka-system-pole-xs-13cm-aluminum-2","status":"publish","type":"product","link":"https:\/\/mediatrade.fi\/en\/product\/mka-system-pole-xs-13cm-aluminum-2\/","title":{"rendered":"m!ka System Pole XS (13cm) &#8211; aluminum"},"content":{"rendered":"\n<section class=\"block block-woocommerce-product-description container-fluid container-fluid \">\n    <div class=\"container\">\n        <div class=\"row\">\n            <div class=\"col-12 col-md-6 order-2 order-md-1 attachments-col\">\n                                            <\/div>\n\n            <div class=\"col-12 col-md-5 offset-md-1 order-1 order-md-2\">\n                <main class=\"entry-content\">\n                    \n\n<h2 class=\"wp-block-heading\">Product<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Aluminium 13 cm System pole for m!ka<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Features<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Four evenly distributed full-height grooves provide four horizontal positions&nbsp;<\/li>\n\n\n\n<li>Mount up to four m!ka items at the same Pole height<\/li>\n\n\n\n<li>Vertical positions and items mounted on top of each other are restricted by Pole height<\/li>\n\n\n\n<li>Available in 4 different standard heights (7,09\u2033 \/ 17,5\u2033 \/ 21,5\u2033 \/ 33,3\u2033)<\/li>\n\n\n\n<li>Customized heights up to 3m (118\u2033) on request<\/li>\n\n\n\n<li>Slide m!ka Monitor Arms into the grooves to fix them<\/li>\n\n\n\n<li>To arrange m!ka Mic Arms or m!ka EasyLift use a m!ka Pole Adapter<\/li>\n\n\n\n<li>One additional m!ka Mic Arm plugs into top<\/li>\n\n\n\n<li>Optionally mount a litt Signaling Device on top of the System Pole<\/li>\n\n\n\n<li>Make use of various m!ka System Pole Support items to fix the Pole to your desk or ceiling<\/li>\n\n\n\n<li>Internal steel thread for desk mounting on the bottom&nbsp;<\/li>\n\n\n\n<li>Black cover cap for top included<\/li>\n<\/ul>\n\n\n                <\/main>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\n\n    \n\n<section class=\"block woocommerce-similar-products container-fluid \">\n    \n<div class=\"partial-block-header\">\n    <div class=\"container\">\n        <div class=\"row align-items-center\">\n            <div class=\"col col-12 col-md-6 d-flex justify-content-start title-col\">\n                                <h2 class=\"block-title\">Liittyv\u00e4t tuotteet<\/h2>\n                            <\/div>\n            <div class=\"col col-12 col-md-6 d-flex justify-content-md-end cta-col\">\n                            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n    <div class=\"container\">\n                <div class=\"row card-row\">\n            <div class=\"col\">\n                \n<div class=\"swiper\">\n            <div class=\"slide\">\n            <div class=\"card product product-feature-tracking\" onclick=\"document.getElementById('card-link-6a97ae33067c8').click();\" data-product='{\"title\":\"m!ka CamStud &#8211; black\",\"sku\":\"YT3277\",\"price\":\"114\",\"brand_name\":\"Yellowtec\",\"link\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/mka-camstud-black-2\\\/\"}'>\n    <div class=\"thumbnail-wrap\">\n        <a href=\"https:\/\/mediatrade.fi\/en\/product\/mka-camstud-black-2\/\" title=\"m!ka CamStud &#8211; black\">\n            <div class=\"card-thumbnail\">\n                <img decoding=\"async\" width=\"300\" height=\"266\" src=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/02\/yt3277_1-300x266.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/02\/yt3277_1-300x266.jpg 300w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/02\/yt3277_1-600x533.jpg 600w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/02\/yt3277_1-338x300.jpg 338w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/02\/yt3277_1.jpg 677w\" sizes=\"300px\" \/>            <\/div>\n        <\/a>\n\n        <div class=\"product-tags\">\n            \n            \n            \n                    <\/div>\n    <\/div>\n    <div class=\"card-content\">\n                <div class=\"brand\">\n            <a class=\"brand-link\" href=\"https:\/\/mediatrade.fi\/en\/tuote-osasto\/all-products\/?brands=yellowtec\">Yellowtec<\/a>\n        <\/div>\n                <h3 class=\"h3 card-title\"><a class=\"product-card-link\" id=\"card-link-6a97ae33067c8\" href=\"https:\/\/mediatrade.fi\/en\/product\/mka-camstud-black-2\/\" rel=\"bookmark\">m!ka CamStud &#8211; black<\/a><\/h3>                    <div class=\"price\">\n                114&nbsp;&euro;<span class=\"tax\">(VAT 0%)<\/span>\n            <\/div>\n                    <\/div>\n<\/div>\n        <\/div>\n            <div class=\"slide\">\n            <div class=\"card product product-feature-tracking\" onclick=\"document.getElementById('card-link-6a97ae330a1db').click();\" data-product='{\"title\":\"m!ka Monitor Arm M \\u2013 black\",\"sku\":\"YT3630\",\"price\":\"266\",\"brand_name\":\"Yellowtec\",\"link\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/mka-monitor-arm-m-black-2\\\/\"}'>\n    <div class=\"thumbnail-wrap\">\n        <a href=\"https:\/\/mediatrade.fi\/en\/product\/mka-monitor-arm-m-black-2\/\" title=\"m!ka Monitor Arm M \u2013 black\">\n            <div class=\"card-thumbnail\">\n                <img decoding=\"async\" width=\"300\" height=\"205\" src=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/02\/yt3630-300x205.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/02\/yt3630-300x205.jpg 300w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/02\/yt3630-600x410.jpg 600w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/02\/yt3630-439x300.jpg 439w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/02\/yt3630.jpg 720w\" sizes=\"300px\" \/>            <\/div>\n        <\/a>\n\n        <div class=\"product-tags\">\n            \n            \n            \n                    <\/div>\n    <\/div>\n    <div class=\"card-content\">\n                <div class=\"brand\">\n            <a class=\"brand-link\" href=\"https:\/\/mediatrade.fi\/en\/tuote-osasto\/all-products\/?brands=yellowtec\">Yellowtec<\/a>\n        <\/div>\n                <h3 class=\"h3 card-title\"><a class=\"product-card-link\" id=\"card-link-6a97ae330a1db\" href=\"https:\/\/mediatrade.fi\/en\/product\/mka-monitor-arm-m-black-2\/\" rel=\"bookmark\">m!ka Monitor Arm M \u2013 black<\/a><\/h3>                    <div class=\"price\">\n                266&nbsp;&euro;<span class=\"tax\">(VAT 0%)<\/span>\n            <\/div>\n                    <\/div>\n<\/div>\n        <\/div>\n            <div class=\"slide\">\n            <div class=\"card product product-feature-tracking\" onclick=\"document.getElementById('card-link-6a97ae330aec6').click();\" data-product='{\"title\":\"m!ka System Pole L (84,5 cm) &#8211; black\",\"sku\":\"YT3641\",\"price\":\"154\",\"brand_name\":\"Yellowtec\",\"link\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/mka-system-pole-l-845-cm-black-2\\\/\"}'>\n    <div class=\"thumbnail-wrap\">\n        <a href=\"https:\/\/mediatrade.fi\/en\/product\/mka-system-pole-l-845-cm-black-2\/\" title=\"m!ka System Pole L (84,5 cm) &#8211; black\">\n            <div class=\"card-thumbnail\">\n                <img decoding=\"async\" width=\"300\" height=\"201\" src=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/02\/SystemPoles-300x201.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/02\/SystemPoles-300x201.jpg 300w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/02\/SystemPoles-600x401.jpg 600w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/02\/SystemPoles-449x300.jpg 449w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/02\/SystemPoles.jpg 767w\" sizes=\"300px\" \/>            <\/div>\n        <\/a>\n\n        <div class=\"product-tags\">\n            \n            \n            \n                    <\/div>\n    <\/div>\n    <div class=\"card-content\">\n                <div class=\"brand\">\n            <a class=\"brand-link\" href=\"https:\/\/mediatrade.fi\/en\/tuote-osasto\/all-products\/?brands=yellowtec\">Yellowtec<\/a>\n        <\/div>\n                <h3 class=\"h3 card-title\"><a class=\"product-card-link\" id=\"card-link-6a97ae330aec6\" href=\"https:\/\/mediatrade.fi\/en\/product\/mka-system-pole-l-845-cm-black-2\/\" rel=\"bookmark\">m!ka System Pole L (84,5 cm) &#8211; black<\/a><\/h3>                    <div class=\"price\">\n                154&nbsp;&euro;<span class=\"tax\">(VAT 0%)<\/span>\n            <\/div>\n                    <\/div>\n<\/div>\n        <\/div>\n            <div class=\"slide\">\n            <div class=\"card product product-feature-tracking\" onclick=\"document.getElementById('card-link-6a97ae330baf8').click();\" data-product='{\"title\":\"m!ka System Pole M (54,5 cm) &#8211; black\",\"sku\":\"YT3643\",\"price\":\"116\",\"brand_name\":\"Yellowtec\",\"link\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/mka-system-pole-m-545-cm-black-2\\\/\"}'>\n    <div class=\"thumbnail-wrap\">\n        <a href=\"https:\/\/mediatrade.fi\/en\/product\/mka-system-pole-m-545-cm-black-2\/\" title=\"m!ka System Pole M (54,5 cm) &#8211; black\">\n            <div class=\"card-thumbnail\">\n                <img decoding=\"async\" width=\"300\" height=\"201\" src=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/02\/SystemPoles-300x201.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/02\/SystemPoles-300x201.jpg 300w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/02\/SystemPoles-600x401.jpg 600w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/02\/SystemPoles-449x300.jpg 449w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/02\/SystemPoles.jpg 767w\" sizes=\"300px\" \/>            <\/div>\n        <\/a>\n\n        <div class=\"product-tags\">\n            \n            \n            \n                    <\/div>\n    <\/div>\n    <div class=\"card-content\">\n                <div class=\"brand\">\n            <a class=\"brand-link\" href=\"https:\/\/mediatrade.fi\/en\/tuote-osasto\/all-products\/?brands=yellowtec\">Yellowtec<\/a>\n        <\/div>\n                <h3 class=\"h3 card-title\"><a class=\"product-card-link\" id=\"card-link-6a97ae330baf8\" href=\"https:\/\/mediatrade.fi\/en\/product\/mka-system-pole-m-545-cm-black-2\/\" rel=\"bookmark\">m!ka System Pole M (54,5 cm) &#8211; black<\/a><\/h3>                    <div class=\"price\">\n                116&nbsp;&euro;<span class=\"tax\">(VAT 0%)<\/span>\n            <\/div>\n                    <\/div>\n<\/div>\n        <\/div>\n            <div class=\"slide\">\n            <div class=\"card product product-feature-tracking\" onclick=\"document.getElementById('card-link-6a97ae330c4b0').click();\" data-product='{\"title\":\"m!ka Wall Mount Pole S (44,5 cm) &#8211; aluminum\",\"sku\":\"YT3260\",\"price\":\"98\",\"brand_name\":\"Yellowtec\",\"link\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/mka-wall-mount-pole-s-445-cm-aluminum-2\\\/\"}'>\n    <div class=\"thumbnail-wrap\">\n        <a href=\"https:\/\/mediatrade.fi\/en\/product\/mka-wall-mount-pole-s-445-cm-aluminum-2\/\" title=\"m!ka Wall Mount Pole S (44,5 cm) &#8211; aluminum\">\n            <div class=\"card-thumbnail\">\n                <img decoding=\"async\" width=\"295\" height=\"300\" src=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/02\/yt3260-295x300.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/02\/yt3260-295x300.jpg 295w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/02\/yt3260.jpg 563w\" sizes=\"295px\" \/>            <\/div>\n        <\/a>\n\n        <div class=\"product-tags\">\n            \n            \n            \n                    <\/div>\n    <\/div>\n    <div class=\"card-content\">\n                <div class=\"brand\">\n            <a class=\"brand-link\" href=\"https:\/\/mediatrade.fi\/en\/tuote-osasto\/all-products\/?brands=yellowtec\">Yellowtec<\/a>\n        <\/div>\n                <h3 class=\"h3 card-title\"><a class=\"product-card-link\" id=\"card-link-6a97ae330c4b0\" href=\"https:\/\/mediatrade.fi\/en\/product\/mka-wall-mount-pole-s-445-cm-aluminum-2\/\" rel=\"bookmark\">m!ka Wall Mount Pole S (44,5 cm) &#8211; aluminum<\/a><\/h3>                    <div class=\"price\">\n                98&nbsp;&euro;<span class=\"tax\">(VAT 0%)<\/span>\n            <\/div>\n                    <\/div>\n<\/div>\n        <\/div>\n            <div class=\"slide\">\n            <div class=\"card product product-feature-tracking\" onclick=\"document.getElementById('card-link-6a97ae330d071').click();\" data-product='{\"title\":\"m!ka Wall Mount Pole XL (89 cm) &#8211; aluminum\",\"sku\":\"YT3261\",\"price\":\"144\",\"brand_name\":\"Yellowtec\",\"link\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/mka-wall-mount-pole-xl-89-cm-aluminum-2\\\/\"}'>\n    <div class=\"thumbnail-wrap\">\n        <a href=\"https:\/\/mediatrade.fi\/en\/product\/mka-wall-mount-pole-xl-89-cm-aluminum-2\/\" title=\"m!ka Wall Mount Pole XL (89 cm) &#8211; aluminum\">\n            <div class=\"card-thumbnail\">\n                <img decoding=\"async\" width=\"295\" height=\"300\" src=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/02\/yt3260-295x300.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/02\/yt3260-295x300.jpg 295w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/02\/yt3260.jpg 563w\" sizes=\"295px\" \/>            <\/div>\n        <\/a>\n\n        <div class=\"product-tags\">\n            \n            \n            \n                    <\/div>\n    <\/div>\n    <div class=\"card-content\">\n                <div class=\"brand\">\n            <a class=\"brand-link\" href=\"https:\/\/mediatrade.fi\/en\/tuote-osasto\/all-products\/?brands=yellowtec\">Yellowtec<\/a>\n        <\/div>\n                <h3 class=\"h3 card-title\"><a class=\"product-card-link\" id=\"card-link-6a97ae330d071\" href=\"https:\/\/mediatrade.fi\/en\/product\/mka-wall-mount-pole-xl-89-cm-aluminum-2\/\" rel=\"bookmark\">m!ka Wall Mount Pole XL (89 cm) &#8211; aluminum<\/a><\/h3>                    <div class=\"price\">\n                144&nbsp;&euro;<span class=\"tax\">(VAT 0%)<\/span>\n            <\/div>\n                    <\/div>\n<\/div>\n        <\/div>\n        <\/div>            <\/div>\n        <\/div>\n            <\/div>\n<\/section>\n\n\n\n<section class=\"block block-profile-listing container-fluid \">\n    <div class=\"container\">\n        <div class=\"row\">\n            <main class=\"entry-content col-12\">\n                \n\n<h2 class=\"wp-block-heading\">Asiantuntijamme<\/h2>\n\n\n            <\/main>\n                        <div class=\"col-12 col-lg-6\">\n                <div class=\"person-wrapper\">\n                    <div class=\"image-wrapper\">\n                        <img decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/Esa_Lo\u0308tjo\u0308nen-576x1024-1.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/Esa_Lo\u0308tjo\u0308nen-576x1024-1.jpg 576w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/Esa_Lo\u0308tjo\u0308nen-576x1024-1-169x300.jpg 169w\" sizes=\"(max-width: 575px) 100vw, (max-width: 767px) 570, (max-width: 991px) 830, (max-width: 1199px) 930, 994px\" \/>                    <\/div>\n                    <div class=\"content-wrapper\">\n                        <h4 class=\"name\">Esa L\u00f6tj\u00f6nen<\/h4>\n                        <p class=\"title\">Senior Specialist, Audio<\/p>\n                        <p class=\"summary\">I manage radio content production and the technical operating environment. I also specialize in complete audio production solutions, from podcast studios to national radio channels.<\/p>\n                                                <span class=\"knowledge-title\">Area of expertise<\/span>\n                        <p class=\"knowledge\">Audio, Broadcasting and transmission, program production<\/p>\n                                                <p class=\"phone\">+358201557722<\/p>\n                        <p class=\"email\">esa.lotjonen@mediatrade.fi<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"col-12 col-lg-6\">\n                <div class=\"person-wrapper\">\n                    <div class=\"image-wrapper\">\n                        <img decoding=\"async\" width=\"1152\" height=\"2048\" src=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/I82A6513.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/I82A6513.jpg 1152w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/I82A6513-169x300.jpg 169w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/I82A6513-576x1024.jpg 576w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/I82A6513-768x1365.jpg 768w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/I82A6513-864x1536.jpg 864w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/I82A6513-600x1067.jpg 600w\" sizes=\"(max-width: 575px) 100vw, (max-width: 767px) 570, (max-width: 991px) 830, (max-width: 1199px) 930, 994px\" \/>                    <\/div>\n                    <div class=\"content-wrapper\">\n                        <h4 class=\"name\">Janne Trogen<\/h4>\n                        <p class=\"title\">Product Manager<\/p>\n                        <p class=\"summary\">With 30 years of experience in broadcast and transmission installations, I handle audio and intercom equipment, as well as projects and installations, at Mediatrade.\r\n<\/p>\n                                                <span class=\"knowledge-title\">Area of expertise<\/span>\n                        <p class=\"knowledge\">Audio, Broadcast and Transmission, Events<\/p>\n                                                <p class=\"phone\">+358201557721<\/p>\n                        <p class=\"email\">janne.trogen@mediatrade.fi<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                                <\/div>\n    <\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":433314,"template":"","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":""},"product_brand":[],"product_cat":[202,2486,2500,9057,15,3492,203,8189],"product_tag":[6855,6683,6873],"brands":[4994],"id_product_type":[],"class_list":["post-382212","product","type-product","status-publish","has-post-thumbnail","product_cat-aani","product_cat-all-products","product_cat-audio","product_cat-in-store","product_cat-kaikki","product_cat-studio-devices-equipment","product_cat-studiolaitteet-tarvikkeet","product_cat-varastossa","product_tag-asennus","product_tag-mka","product_tag-system-pole","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":2,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>m!ka System Pole XS (13cm) - aluminum - Mediatrade<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mediatrade.fi\/en\/product\/mka-system-pole-xs-13cm-aluminum-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"m!ka System Pole XS (13cm) - aluminum - Mediatrade\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mediatrade.fi\/en\/product\/mka-system-pole-xs-13cm-aluminum-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Mediatrade\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-23T10:24:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/02\/SystemPoles.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"767\" \/>\n\t<meta property=\"og:image:height\" content=\"513\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/mka-system-pole-xs-13cm-aluminum-2\\\/\",\"url\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/mka-system-pole-xs-13cm-aluminum-2\\\/\",\"name\":\"m!ka System Pole XS (13cm) - aluminum - Mediatrade\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/mka-system-pole-xs-13cm-aluminum-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/mka-system-pole-xs-13cm-aluminum-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mediatrade.fi\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/SystemPoles.jpg\",\"datePublished\":\"2025-01-21T15:44:54+00:00\",\"dateModified\":\"2026-01-23T10:24:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/mka-system-pole-xs-13cm-aluminum-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/mka-system-pole-xs-13cm-aluminum-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/mka-system-pole-xs-13cm-aluminum-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mediatrade.fi\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/SystemPoles.jpg\",\"contentUrl\":\"https:\\\/\\\/mediatrade.fi\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/SystemPoles.jpg\",\"width\":767,\"height\":513},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/mka-system-pole-xs-13cm-aluminum-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Etusivu\",\"item\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"m!ka System Pole XS (13cm) &#8211; aluminum\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/\",\"name\":\"Mediatrade\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/#organization\",\"name\":\"Mediatrade\",\"url\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mediatrade.fi\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Group-640.svg\",\"contentUrl\":\"https:\\\/\\\/mediatrade.fi\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Group-640.svg\",\"width\":128,\"height\":43,\"caption\":\"Mediatrade\"},\"image\":{\"@id\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"m!ka System Pole XS (13cm) - aluminum - Mediatrade","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mediatrade.fi\/en\/product\/mka-system-pole-xs-13cm-aluminum-2\/","og_locale":"en_US","og_type":"article","og_title":"m!ka System Pole XS (13cm) - aluminum - Mediatrade","og_url":"https:\/\/mediatrade.fi\/en\/product\/mka-system-pole-xs-13cm-aluminum-2\/","og_site_name":"Mediatrade","article_modified_time":"2026-01-23T10:24:12+00:00","og_image":[{"width":767,"height":513,"url":"https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/02\/SystemPoles.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mediatrade.fi\/en\/product\/mka-system-pole-xs-13cm-aluminum-2\/","url":"https:\/\/mediatrade.fi\/en\/product\/mka-system-pole-xs-13cm-aluminum-2\/","name":"m!ka System Pole XS (13cm) - aluminum - Mediatrade","isPartOf":{"@id":"https:\/\/mediatrade.fi\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mediatrade.fi\/en\/product\/mka-system-pole-xs-13cm-aluminum-2\/#primaryimage"},"image":{"@id":"https:\/\/mediatrade.fi\/en\/product\/mka-system-pole-xs-13cm-aluminum-2\/#primaryimage"},"thumbnailUrl":"https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/02\/SystemPoles.jpg","datePublished":"2025-01-21T15:44:54+00:00","dateModified":"2026-01-23T10:24:12+00:00","breadcrumb":{"@id":"https:\/\/mediatrade.fi\/en\/product\/mka-system-pole-xs-13cm-aluminum-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mediatrade.fi\/en\/product\/mka-system-pole-xs-13cm-aluminum-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mediatrade.fi\/en\/product\/mka-system-pole-xs-13cm-aluminum-2\/#primaryimage","url":"https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/02\/SystemPoles.jpg","contentUrl":"https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/02\/SystemPoles.jpg","width":767,"height":513},{"@type":"BreadcrumbList","@id":"https:\/\/mediatrade.fi\/en\/product\/mka-system-pole-xs-13cm-aluminum-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Etusivu","item":"https:\/\/mediatrade.fi\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/mediatrade.fi\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"m!ka System Pole XS (13cm) &#8211; aluminum"}]},{"@type":"WebSite","@id":"https:\/\/mediatrade.fi\/en\/#website","url":"https:\/\/mediatrade.fi\/en\/","name":"Mediatrade","description":"","publisher":{"@id":"https:\/\/mediatrade.fi\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mediatrade.fi\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mediatrade.fi\/en\/#organization","name":"Mediatrade","url":"https:\/\/mediatrade.fi\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mediatrade.fi\/en\/#\/schema\/logo\/image\/","url":"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/Group-640.svg","contentUrl":"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/Group-640.svg","width":128,"height":43,"caption":"Mediatrade"},"image":{"@id":"https:\/\/mediatrade.fi\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mediatrade.fi\/en\/wp-json\/wp\/v2\/product\/382212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mediatrade.fi\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mediatrade.fi\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mediatrade.fi\/en\/wp-json\/wp\/v2\/media\/433314"}],"wp:attachment":[{"href":"https:\/\/mediatrade.fi\/en\/wp-json\/wp\/v2\/media?parent=382212"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mediatrade.fi\/en\/wp-json\/wp\/v2\/product_brand?post=382212"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mediatrade.fi\/en\/wp-json\/wp\/v2\/product_cat?post=382212"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mediatrade.fi\/en\/wp-json\/wp\/v2\/product_tag?post=382212"},{"taxonomy":"brands","embeddable":true,"href":"https:\/\/mediatrade.fi\/en\/wp-json\/wp\/v2\/brands?post=382212"},{"taxonomy":"id_product_type","embeddable":true,"href":"https:\/\/mediatrade.fi\/en\/wp-json\/wp\/v2\/id_product_type?post=382212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}