{"id":395153,"date":"2022-05-04T10:20:54","date_gmt":"2025-01-21T20:22:16","guid":{"rendered":"https:\/\/mediatrade.fi\/tuote\/snapbox-4-x-2-led-tiles-2\/"},"modified":"2025-02-04T23:26:59","modified_gmt":"2025-02-04T21:26:59","slug":"snapbox-4-x-2-led-tiles-2","status":"publish","type":"product","link":"https:\/\/mediatrade.fi\/en\/product\/snapbox-4-x-2-led-tiles-2\/","title":{"rendered":"SNAPBOX 4\u00b4 x 2\u00b4 LED Tiles"},"content":{"rendered":"\n<section class=\"block block-woocommerce-product-description container-fluid container-fluid \">\n    <div class=\"container\">\n        <div class=\"row\">\n            <div class=\"col-12 col-md-6 order-2 order-md-1 attachments-col\">\n                                <div style=\"height: 100%;\" class=\"oembed oembed-youtube\">        <div class=\"cookieconsent-optout-marketing\">            <a href=\"javascript:Cookiebot.renew()\">Hyv\u00e4ksy markkinointiev\u00e4steet<\/a>            katsoaksesi videon.        <\/div><iframe title=\"SNAPBOX Adapter Instructions: KINO FLO FS 48 LED Tubes\" width=\"840\" height=\"473\" src=\"https:\/\/www.youtube.com\/embed\/ZwJ68H9Jq0o?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div>            <\/div>\n\n            <div class=\"col-12 col-md-5 offset-md-1 order-1 order-md-2\">\n                <main class=\"entry-content\">\n                    \n\n<h2 class=\"wp-block-heading\">Tuotetiedot<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Including SNAPBOX, 4 Side Diffuser, 4 Side Cover, 1 Front Diffuser and Carry Bag<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fits on the 2x LiteGear Lite Tile 4&#8217;x2&#8242;, Carpetlight CL44 etc. incl. diffusion MAGIC cloth and carry bag (former SBLT44)<\/p>\n\n\n                <\/main>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\n\n    \n\n<section class=\"block woocommerce-similar-products container-fluid \">\n    \n<div class=\"partial-block-header\">\n    <div class=\"container\">\n        <div class=\"row align-items-center\">\n            <div class=\"col col-12 col-md-6 d-flex justify-content-start title-col\">\n                                <h2 class=\"block-title\">Liittyv\u00e4t tuotteet<\/h2>\n                            <\/div>\n            <div class=\"col col-12 col-md-6 d-flex justify-content-md-end cta-col\">\n                            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n    <div class=\"container\">\n                <div class=\"row card-row\">\n            <div class=\"col\">\n                \n<div class=\"swiper\">\n            <div class=\"slide\">\n            <div class=\"card product product-feature-tracking\" onclick=\"document.getElementById('card-link-6a97b454185c0').click();\" data-product='{\"title\":\"SNAPBOX 4\\u00b4 x 4\\u00b4 LED Tiles\",\"sku\":\"SXF44\",\"price\":\"1049\",\"brand_name\":\"DopChoice\",\"link\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/snapbox-4-x-4-led-tiles-2\\\/\"}'>\n    <div class=\"thumbnail-wrap\">\n        <a href=\"https:\/\/mediatrade.fi\/en\/product\/snapbox-4-x-4-led-tiles-2\/\" title=\"SNAPBOX 4\u00b4 x 4\u00b4 LED Tiles\">\n            <div class=\"card-thumbnail\">\n                <img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/dopchoice-snapbox4x4led-tiles-300x300.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/dopchoice-snapbox4x4led-tiles-300x300.jpg 300w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/dopchoice-snapbox4x4led-tiles-150x150.jpg 150w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/dopchoice-snapbox4x4led-tiles-768x768.jpg 768w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/dopchoice-snapbox4x4led-tiles-600x600.jpg 600w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/dopchoice-snapbox4x4led-tiles-100x100.jpg 100w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/dopchoice-snapbox4x4led-tiles.jpg 800w\" sizes=\"300px\" \/>            <\/div>\n        <\/a>\n\n        <div class=\"product-tags\">\n            \n            \n            \n                    <\/div>\n    <\/div>\n    <div class=\"card-content\">\n                <div class=\"brand\">\n            <a class=\"brand-link\" href=\"https:\/\/mediatrade.fi\/en\/tuote-osasto\/all-products\/?brands=dopchoice\">DopChoice<\/a>\n        <\/div>\n                <h3 class=\"h3 card-title\"><a class=\"product-card-link\" id=\"card-link-6a97b454185c0\" href=\"https:\/\/mediatrade.fi\/en\/product\/snapbox-4-x-4-led-tiles-2\/\" rel=\"bookmark\">SNAPBOX 4\u00b4 x 4\u00b4 LED Tiles<\/a><\/h3>                    <div class=\"price\">\n                1049&nbsp;&euro;<span class=\"tax\">(VAT 0%)<\/span>\n            <\/div>\n                    <\/div>\n<\/div>\n        <\/div>\n            <div class=\"slide\">\n            <div class=\"card product product-feature-tracking\" onclick=\"document.getElementById('card-link-6a97b45419bc2').click();\" data-product='{\"title\":\"SNAPGRID\\u00ae 40\\u00b0 for SNAPBOX\\u2122 SXF82\",\"sku\":\"SGSBX82W40\",\"price\":\"944\",\"brand_name\":\"DopChoice\",\"link\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/snapgrid-40-for-snapbox-sxf82-2\\\/\"}'>\n    <div class=\"thumbnail-wrap\">\n        <a href=\"https:\/\/mediatrade.fi\/en\/product\/snapgrid-40-for-snapbox-sxf82-2\/\" title=\"SNAPGRID\u00ae 40\u00b0 for SNAPBOX\u2122 SXF82\">\n            <div class=\"card-thumbnail\">\n                <img decoding=\"async\" width=\"300\" height=\"183\" src=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/dopchoice-snapgrid40degforsnapbox-sblt82-300x183.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/dopchoice-snapgrid40degforsnapbox-sblt82-300x183.jpg 300w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/dopchoice-snapgrid40degforsnapbox-sblt82-768x469.jpg 768w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/dopchoice-snapgrid40degforsnapbox-sblt82-600x366.jpg 600w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/dopchoice-snapgrid40degforsnapbox-sblt82-491x300.jpg 491w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/dopchoice-snapgrid40degforsnapbox-sblt82.jpg 960w\" sizes=\"300px\" \/>            <\/div>\n        <\/a>\n\n        <div class=\"product-tags\">\n            \n            \n            \n                    <\/div>\n    <\/div>\n    <div class=\"card-content\">\n                <div class=\"brand\">\n            <a class=\"brand-link\" href=\"https:\/\/mediatrade.fi\/en\/tuote-osasto\/all-products\/?brands=dopchoice\">DopChoice<\/a>\n        <\/div>\n                <h3 class=\"h3 card-title\"><a class=\"product-card-link\" id=\"card-link-6a97b45419bc2\" href=\"https:\/\/mediatrade.fi\/en\/product\/snapgrid-40-for-snapbox-sxf82-2\/\" rel=\"bookmark\">SNAPGRID\u00ae 40\u00b0 for SNAPBOX\u2122 SXF82<\/a><\/h3>                    <div class=\"price\">\n                944&nbsp;&euro;<span class=\"tax\">(VAT 0%)<\/span>\n            <\/div>\n                    <\/div>\n<\/div>\n        <\/div>\n            <div class=\"slide\">\n            <div class=\"card product product-feature-tracking\" onclick=\"document.getElementById('card-link-6a97b4541a868').click();\" data-product='{\"title\":\"SNAPGRID 40\\u00b0 for SNAPBOX SXF84\",\"sku\":\"SGSBX84W40\",\"price\":\"1607\",\"brand_name\":\"DopChoice\",\"link\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/snapgrid-40-for-snapbox-sxf84-2\\\/\"}'>\n    <div class=\"thumbnail-wrap\">\n        <a href=\"https:\/\/mediatrade.fi\/en\/product\/snapgrid-40-for-snapbox-sxf84-2\/\" title=\"SNAPGRID 40\u00b0 for SNAPBOX SXF84\">\n            <div class=\"card-thumbnail\">\n                <img decoding=\"async\" width=\"300\" height=\"183\" src=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/dopchoice-snapgrid40degforsnapbox-sblt84-300x183.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/dopchoice-snapgrid40degforsnapbox-sblt84-300x183.jpg 300w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/dopchoice-snapgrid40degforsnapbox-sblt84-768x469.jpg 768w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/dopchoice-snapgrid40degforsnapbox-sblt84-600x366.jpg 600w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/dopchoice-snapgrid40degforsnapbox-sblt84-491x300.jpg 491w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/dopchoice-snapgrid40degforsnapbox-sblt84.jpg 960w\" sizes=\"300px\" \/>            <\/div>\n        <\/a>\n\n        <div class=\"product-tags\">\n            \n            \n            \n                    <\/div>\n    <\/div>\n    <div class=\"card-content\">\n                <div class=\"brand\">\n            <a class=\"brand-link\" href=\"https:\/\/mediatrade.fi\/en\/tuote-osasto\/all-products\/?brands=dopchoice\">DopChoice<\/a>\n        <\/div>\n                <h3 class=\"h3 card-title\"><a class=\"product-card-link\" id=\"card-link-6a97b4541a868\" href=\"https:\/\/mediatrade.fi\/en\/product\/snapgrid-40-for-snapbox-sxf84-2\/\" rel=\"bookmark\">SNAPGRID 40\u00b0 for SNAPBOX SXF84<\/a><\/h3>                    <div class=\"price\">\n                1607&nbsp;&euro;<span class=\"tax\">(VAT 0%)<\/span>\n            <\/div>\n                    <\/div>\n<\/div>\n        <\/div>\n            <div class=\"slide\">\n            <div class=\"card product product-feature-tracking\" onclick=\"document.getElementById('card-link-6a97b4541b4ed').click();\" data-product='{\"title\":\"Astera Adapter for SNAPBOX 4\\u00b4 x 4\\u00b4\",\"sku\":\"SXF44-AA8\",\"price\":\"273\",\"brand_name\":\"DopChoice\",\"link\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/astera-adapter-for-snapbox-4-x-4-2\\\/\"}'>\n    <div class=\"thumbnail-wrap\">\n        <a href=\"https:\/\/mediatrade.fi\/en\/product\/astera-adapter-for-snapbox-4-x-4-2\/\" title=\"Astera Adapter for SNAPBOX 4\u00b4 x 4\u00b4\">\n            <div class=\"card-thumbnail\">\n                <img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/dopchoice-asteraadapterforsnapbox4x-4-300x300.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/dopchoice-asteraadapterforsnapbox4x-4-300x300.jpg 300w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/dopchoice-asteraadapterforsnapbox4x-4-150x150.jpg 150w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/dopchoice-asteraadapterforsnapbox4x-4-768x768.jpg 768w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/dopchoice-asteraadapterforsnapbox4x-4-600x600.jpg 600w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/dopchoice-asteraadapterforsnapbox4x-4-100x100.jpg 100w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/dopchoice-asteraadapterforsnapbox4x-4.jpg 800w\" sizes=\"300px\" \/>            <\/div>\n        <\/a>\n\n        <div class=\"product-tags\">\n            \n            \n            \n                    <\/div>\n    <\/div>\n    <div class=\"card-content\">\n                <div class=\"brand\">\n            <a class=\"brand-link\" href=\"https:\/\/mediatrade.fi\/en\/tuote-osasto\/all-products\/?brands=dopchoice\">DopChoice<\/a>\n        <\/div>\n                <h3 class=\"h3 card-title\"><a class=\"product-card-link\" id=\"card-link-6a97b4541b4ed\" href=\"https:\/\/mediatrade.fi\/en\/product\/astera-adapter-for-snapbox-4-x-4-2\/\" rel=\"bookmark\">Astera Adapter for SNAPBOX 4\u00b4 x 4\u00b4<\/a><\/h3>                    <div class=\"price\">\n                273&nbsp;&euro;<span class=\"tax\">(VAT 0%)<\/span>\n            <\/div>\n                    <\/div>\n<\/div>\n        <\/div>\n            <div class=\"slide\">\n            <div class=\"card product product-feature-tracking\" onclick=\"document.getElementById('card-link-6a97b4541c155').click();\" data-product='{\"title\":\"Snapbox SXLM1 &#8211; for Litegear &amp; Kinoflo\",\"sku\":\"SXLM1\",\"price\":\"190\",\"brand_name\":\"DopChoice\",\"link\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/snapbox-sxlm1-for-litegear-kinoflo-2\\\/\"}'>\n    <div class=\"thumbnail-wrap\">\n        <a href=\"https:\/\/mediatrade.fi\/en\/product\/snapbox-sxlm1-for-litegear-kinoflo-2\/\" title=\"Snapbox SXLM1 &#8211; for Litegear &amp; Kinoflo\">\n            <div class=\"card-thumbnail\">\n                <img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/04\/SXLM1_4-300x300.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/04\/SXLM1_4-300x300.webp 300w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/04\/SXLM1_4-400x400.webp 400w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/04\/SXLM1_4-600x600.webp 600w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/04\/SXLM1_4-150x150.webp 150w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/04\/SXLM1_4-768x768.webp 768w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/04\/SXLM1_4-1024x1024.webp 1024w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/04\/SXLM1_4-1536x1536.webp 1536w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/04\/SXLM1_4-2048x2048.webp 2048w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/04\/SXLM1_4-1920x1920.webp 1920w\" sizes=\"300px\" \/>            <\/div>\n        <\/a>\n\n        <div class=\"product-tags\">\n            \n            \n            \n                    <\/div>\n    <\/div>\n    <div class=\"card-content\">\n                <div class=\"brand\">\n            <a class=\"brand-link\" href=\"https:\/\/mediatrade.fi\/en\/tuote-osasto\/all-products\/?brands=dopchoice\">DopChoice<\/a>\n        <\/div>\n                <h3 class=\"h3 card-title\"><a class=\"product-card-link\" id=\"card-link-6a97b4541c155\" href=\"https:\/\/mediatrade.fi\/en\/product\/snapbox-sxlm1-for-litegear-kinoflo-2\/\" rel=\"bookmark\">Snapbox SXLM1 &#8211; for Litegear &amp; Kinoflo<\/a><\/h3>                    <div class=\"price\">\n                190&nbsp;&euro;<span class=\"tax\">(VAT 0%)<\/span>\n            <\/div>\n                    <\/div>\n<\/div>\n        <\/div>\n            <div class=\"slide\">\n            <div class=\"card product product-feature-tracking\" onclick=\"document.getElementById('card-link-6a97b4541ce8f').click();\" data-product='{\"title\":\"SNAPBOX SXLM4 &#8211; for Litegear &amp; Kinoflo\",\"sku\":\"SXLM4\",\"price\":\"300\",\"brand_name\":\"\",\"link\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/snapbox-sxlm4-for-litegear-kinoflo-2\\\/\"}'>\n    <div class=\"thumbnail-wrap\">\n        <a href=\"https:\/\/mediatrade.fi\/en\/product\/snapbox-sxlm4-for-litegear-kinoflo-2\/\" title=\"SNAPBOX SXLM4 &#8211; for Litegear &amp; Kinoflo\">\n            <div class=\"card-thumbnail\">\n                <img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/04\/SXLM4_1-1-300x300.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/04\/SXLM4_1-1-300x300.webp 300w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/04\/SXLM4_1-1-400x400.webp 400w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/04\/SXLM4_1-1-600x600.webp 600w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/04\/SXLM4_1-1-150x150.webp 150w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/04\/SXLM4_1-1-768x768.webp 768w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/04\/SXLM4_1-1-1024x1024.webp 1024w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/04\/SXLM4_1-1-1536x1536.webp 1536w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/04\/SXLM4_1-1.webp 1600w\" sizes=\"300px\" \/>            <\/div>\n        <\/a>\n\n        <div class=\"product-tags\">\n            \n            \n            \n                    <\/div>\n    <\/div>\n    <div class=\"card-content\">\n                <h3 class=\"h3 card-title\"><a class=\"product-card-link\" id=\"card-link-6a97b4541ce8f\" href=\"https:\/\/mediatrade.fi\/en\/product\/snapbox-sxlm4-for-litegear-kinoflo-2\/\" rel=\"bookmark\">SNAPBOX SXLM4 &#8211; for Litegear &amp; Kinoflo<\/a><\/h3>                    <div class=\"price\">\n                300&nbsp;&euro;<span class=\"tax\">(VAT 0%)<\/span>\n            <\/div>\n                    <\/div>\n<\/div>\n        <\/div>\n        <\/div>            <\/div>\n        <\/div>\n            <\/div>\n<\/section>\n\n\n\n<section class=\"block block-profile-listing container-fluid \">\n    <div class=\"container\">\n        <div class=\"row\">\n            <main class=\"entry-content col-12\">\n                \n\n<h2 class=\"wp-block-heading\">Asiantuntijat<\/h2>\n\n\n            <\/main>\n                        <div class=\"col-12 col-lg-6\">\n                <div class=\"person-wrapper\">\n                    <div class=\"image-wrapper\">\n                        <img decoding=\"async\" width=\"1920\" height=\"3414\" src=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/Kaposempi-mr.-Tommi-Rosnell-1920x3414.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/Kaposempi-mr.-Tommi-Rosnell-1920x3414.jpg 1920w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/Kaposempi-mr.-Tommi-Rosnell-169x300.jpg 169w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/Kaposempi-mr.-Tommi-Rosnell-576x1024.jpg 576w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/Kaposempi-mr.-Tommi-Rosnell-768x1365.jpg 768w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/Kaposempi-mr.-Tommi-Rosnell-864x1536.jpg 864w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/Kaposempi-mr.-Tommi-Rosnell-1152x2048.jpg 1152w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/Kaposempi-mr.-Tommi-Rosnell-600x1067.jpg 600w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/Kaposempi-mr.-Tommi-Rosnell-scaled.jpg 1440w\" sizes=\"(max-width: 575px) 100vw, (max-width: 767px) 570, (max-width: 991px) 830, (max-width: 1199px) 930, 994px\" \/>                    <\/div>\n                    <div class=\"content-wrapper\">\n                        <h4 class=\"name\">Tommi Rosnell<\/h4>\n                        <p class=\"title\">Business Development Manager<\/p>\n                        <p class=\"summary\">I work as a production lighting specialist at Mediatrade. My expertise lies in designing studio lighting and planning production workflows.<\/p>\n                                                <span class=\"knowledge-title\">Area of expertise<\/span>\n                        <p class=\"knowledge\">Post-production, cinematography, lighting<\/p>\n                                                <p class=\"phone\">+358201557730<\/p>\n                        <p class=\"email\">tommi.rosnell@mediatrade.fi<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                                <\/div>\n    <\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":71266,"template":"","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"67940,63313,63314,67941,121531,121539","_relevanssi_noindex_reason":""},"product_brand":[],"product_cat":[2486,15,3509,3514,43,213],"product_tag":[1479,1480,838,2490,1449,1478],"brands":[608],"id_product_type":[],"class_list":["post-395153","product","type-product","status-publish","has-post-thumbnail","product_cat-all-products","product_cat-kaikki","product_cat-light-en","product_cat-light-modifiers","product_cat-valo","product_cat-valomuokkaimet","product_tag-4x2","product_tag-led-tiles","product_tag-mediatrade","product_tag-mediatrade-en","product_tag-snapbox","product_tag-snapbox-4x2-led-tiles","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"onbackorder","bundle_stock_quantity":0,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SNAPBOX 4\u00b4 x 2\u00b4 LED Tiles - Mediatrade<\/title>\n<meta name=\"description\" content=\"Fits on the LiteGear Lite Tile 2&#039;x4&#039;, Carpetlight CL42 incl. diffusion MAGIC cloth and carry bag (former SBLT42)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mediatrade.fi\/en\/product\/snapbox-4-x-2-led-tiles-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SNAPBOX 4\u00b4 x 2\u00b4 LED Tiles - Mediatrade\" \/>\n<meta property=\"og:description\" content=\"Fits on the LiteGear Lite Tile 2&#039;x4&#039;, Carpetlight CL42 incl. diffusion MAGIC cloth and carry bag (former SBLT42)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mediatrade.fi\/en\/product\/snapbox-4-x-2-led-tiles-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Mediatrade\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-04T21:26:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/dopchoice-ledtiles4x2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/snapbox-4-x-2-led-tiles-2\\\/\",\"url\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/snapbox-4-x-2-led-tiles-2\\\/\",\"name\":\"SNAPBOX 4\u00b4 x 2\u00b4 LED Tiles - Mediatrade\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/snapbox-4-x-2-led-tiles-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/snapbox-4-x-2-led-tiles-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mediatrade.fi\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/dopchoice-ledtiles4x2.jpg\",\"datePublished\":\"2025-01-21T20:22:16+00:00\",\"dateModified\":\"2025-02-04T21:26:59+00:00\",\"description\":\"Fits on the LiteGear Lite Tile 2'x4', Carpetlight CL42 incl. diffusion MAGIC cloth and carry bag (former SBLT42)\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/snapbox-4-x-2-led-tiles-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/snapbox-4-x-2-led-tiles-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/snapbox-4-x-2-led-tiles-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mediatrade.fi\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/dopchoice-ledtiles4x2.jpg\",\"contentUrl\":\"https:\\\/\\\/mediatrade.fi\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/dopchoice-ledtiles4x2.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/snapbox-4-x-2-led-tiles-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Etusivu\",\"item\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SNAPBOX 4\u00b4 x 2\u00b4 LED Tiles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/\",\"name\":\"Mediatrade\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/#organization\",\"name\":\"Mediatrade\",\"url\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mediatrade.fi\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Group-640.svg\",\"contentUrl\":\"https:\\\/\\\/mediatrade.fi\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Group-640.svg\",\"width\":128,\"height\":43,\"caption\":\"Mediatrade\"},\"image\":{\"@id\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SNAPBOX 4\u00b4 x 2\u00b4 LED Tiles - Mediatrade","description":"Fits on the LiteGear Lite Tile 2'x4', Carpetlight CL42 incl. diffusion MAGIC cloth and carry bag (former SBLT42)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mediatrade.fi\/en\/product\/snapbox-4-x-2-led-tiles-2\/","og_locale":"en_US","og_type":"article","og_title":"SNAPBOX 4\u00b4 x 2\u00b4 LED Tiles - Mediatrade","og_description":"Fits on the LiteGear Lite Tile 2'x4', Carpetlight CL42 incl. diffusion MAGIC cloth and carry bag (former SBLT42)","og_url":"https:\/\/mediatrade.fi\/en\/product\/snapbox-4-x-2-led-tiles-2\/","og_site_name":"Mediatrade","article_modified_time":"2025-02-04T21:26:59+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/dopchoice-ledtiles4x2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mediatrade.fi\/en\/product\/snapbox-4-x-2-led-tiles-2\/","url":"https:\/\/mediatrade.fi\/en\/product\/snapbox-4-x-2-led-tiles-2\/","name":"SNAPBOX 4\u00b4 x 2\u00b4 LED Tiles - Mediatrade","isPartOf":{"@id":"https:\/\/mediatrade.fi\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mediatrade.fi\/en\/product\/snapbox-4-x-2-led-tiles-2\/#primaryimage"},"image":{"@id":"https:\/\/mediatrade.fi\/en\/product\/snapbox-4-x-2-led-tiles-2\/#primaryimage"},"thumbnailUrl":"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/dopchoice-ledtiles4x2.jpg","datePublished":"2025-01-21T20:22:16+00:00","dateModified":"2025-02-04T21:26:59+00:00","description":"Fits on the LiteGear Lite Tile 2'x4', Carpetlight CL42 incl. diffusion MAGIC cloth and carry bag (former SBLT42)","breadcrumb":{"@id":"https:\/\/mediatrade.fi\/en\/product\/snapbox-4-x-2-led-tiles-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mediatrade.fi\/en\/product\/snapbox-4-x-2-led-tiles-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mediatrade.fi\/en\/product\/snapbox-4-x-2-led-tiles-2\/#primaryimage","url":"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/dopchoice-ledtiles4x2.jpg","contentUrl":"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/dopchoice-ledtiles4x2.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/mediatrade.fi\/en\/product\/snapbox-4-x-2-led-tiles-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Etusivu","item":"https:\/\/mediatrade.fi\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/mediatrade.fi\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"SNAPBOX 4\u00b4 x 2\u00b4 LED Tiles"}]},{"@type":"WebSite","@id":"https:\/\/mediatrade.fi\/en\/#website","url":"https:\/\/mediatrade.fi\/en\/","name":"Mediatrade","description":"","publisher":{"@id":"https:\/\/mediatrade.fi\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mediatrade.fi\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mediatrade.fi\/en\/#organization","name":"Mediatrade","url":"https:\/\/mediatrade.fi\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mediatrade.fi\/en\/#\/schema\/logo\/image\/","url":"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/Group-640.svg","contentUrl":"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/Group-640.svg","width":128,"height":43,"caption":"Mediatrade"},"image":{"@id":"https:\/\/mediatrade.fi\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mediatrade.fi\/en\/wp-json\/wp\/v2\/product\/395153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mediatrade.fi\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mediatrade.fi\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mediatrade.fi\/en\/wp-json\/wp\/v2\/media\/71266"}],"wp:attachment":[{"href":"https:\/\/mediatrade.fi\/en\/wp-json\/wp\/v2\/media?parent=395153"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mediatrade.fi\/en\/wp-json\/wp\/v2\/product_brand?post=395153"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mediatrade.fi\/en\/wp-json\/wp\/v2\/product_cat?post=395153"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mediatrade.fi\/en\/wp-json\/wp\/v2\/product_tag?post=395153"},{"taxonomy":"brands","embeddable":true,"href":"https:\/\/mediatrade.fi\/en\/wp-json\/wp\/v2\/brands?post=395153"},{"taxonomy":"id_product_type","embeddable":true,"href":"https:\/\/mediatrade.fi\/en\/wp-json\/wp\/v2\/id_product_type?post=395153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}