{"id":398985,"date":"2022-05-04T08:57:29","date_gmt":"2025-01-21T21:40:50","guid":{"rendered":"https:\/\/mediatrade.fi\/tuote\/light-carry-case-for-1-astra-or-1-gemini-1x1-2\/"},"modified":"2026-03-19T19:15:07","modified_gmt":"2026-03-19T17:15:07","slug":"light-carry-case-for-1-astra-or-1-gemini-1x1-2","status":"publish","type":"product","link":"https:\/\/mediatrade.fi\/en\/product\/light-carry-case-for-1-astra-or-1-gemini-1x1-2\/","title":{"rendered":"Light carry case for (1) Astra or (1) Gemini 1&#215;1"},"content":{"rendered":"\n<section class=\"block block-woocommerce-product-description container-fluid container-fluid \">\n    <div class=\"container\">\n        <div class=\"row\">\n            <div class=\"col-12 col-md-6 order-2 order-md-1 attachments-col\">\n                                            <\/div>\n\n            <div class=\"col-12 col-md-5 offset-md-1 order-1 order-md-2\">\n                <main class=\"entry-content\">\n                    \n\n<h2 class=\"wp-block-heading\">Tuotetiedot<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Comfortably and securely transport one 1&#215;1 fixture with yoke, power supply and gels.<\/p>\n\n\n                <\/main>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\n\n    \n\n<section class=\"block woocommerce-similar-products container-fluid \">\n    \n<div class=\"partial-block-header\">\n    <div class=\"container\">\n        <div class=\"row align-items-center\">\n            <div class=\"col col-12 col-md-6 d-flex justify-content-start title-col\">\n                                <h2 class=\"block-title\">Liittyv\u00e4t tuotteet<\/h2>\n                            <\/div>\n            <div class=\"col col-12 col-md-6 d-flex justify-content-md-end cta-col\">\n                            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n    <div class=\"container\">\n                <div class=\"row card-row\">\n            <div class=\"col\">\n                \n<div class=\"swiper\">\n            <div class=\"slide\">\n            <div class=\"card product product-feature-tracking\" onclick=\"document.getElementById('card-link-6a978ab08a41c').click();\" data-product='{\"title\":\"Light carry case for (2) Astra\\u00b4s or (2) Gemini 1&#215;1\",\"sku\":\"900-3522\",\"price\":\"285\",\"brand_name\":\"Litepanels\",\"link\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/light-carry-case-for-2-astras-or-2-gemini-1x1-2\\\/\"}'>\n    <div class=\"thumbnail-wrap\">\n        <a href=\"https:\/\/mediatrade.fi\/en\/product\/light-carry-case-for-2-astras-or-2-gemini-1x1-2\/\" title=\"Light carry case for (2) Astra\u00b4s or (2) Gemini 1&#215;1\">\n            <div class=\"card-thumbnail\">\n                <img decoding=\"async\" width=\"300\" height=\"269\" src=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/litepanels-lightcarrycasefor2astra1x1s-300x269.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/litepanels-lightcarrycasefor2astra1x1s-300x269.jpg 300w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/litepanels-lightcarrycasefor2astra1x1s-1024x917.jpg 1024w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/litepanels-lightcarrycasefor2astra1x1s-768x687.jpg 768w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/litepanels-lightcarrycasefor2astra1x1s-1536x1375.jpg 1536w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/litepanels-lightcarrycasefor2astra1x1s-2048x1833.jpg 2048w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/litepanels-lightcarrycasefor2astra1x1s-1920x1719.jpg 1920w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/litepanels-lightcarrycasefor2astra1x1s-600x537.jpg 600w\" sizes=\"300px\" \/>            <\/div>\n        <\/a>\n\n        <div class=\"product-tags\">\n            \n            \n            \n                    <\/div>\n    <\/div>\n    <div class=\"card-content\">\n                <div class=\"brand\">\n            <a class=\"brand-link\" href=\"https:\/\/mediatrade.fi\/en\/tuote-osasto\/all-products\/?brands=litepanels\">Litepanels<\/a>\n        <\/div>\n                <h3 class=\"h3 card-title\"><a class=\"product-card-link\" id=\"card-link-6a978ab08a41c\" href=\"https:\/\/mediatrade.fi\/en\/product\/light-carry-case-for-2-astras-or-2-gemini-1x1-2\/\" rel=\"bookmark\">Light carry case for (2) Astra\u00b4s or (2) Gemini 1&#215;1<\/a><\/h3>                    <div class=\"price\">\n                285&nbsp;&euro;<span class=\"tax\">(VAT 0%)<\/span>\n            <\/div>\n                    <\/div>\n<\/div>\n        <\/div>\n            <div class=\"slide\">\n            <div class=\"card product product-feature-tracking\" onclick=\"document.getElementById('card-link-6a978ab08b99f').click();\" data-product='{\"title\":\"Director\\u2019s Monitor Cage for 7\\u201dor 9\\u201d Monitor\",\"sku\":\"HD-1\",\"price\":\"87\",\"brand_name\":\"Portkeys\",\"link\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/directors-monitor-cage-for-7or-9-monitor\\\/\"}'>\n    <div class=\"thumbnail-wrap\">\n        <a href=\"https:\/\/mediatrade.fi\/en\/product\/directors-monitor-cage-for-7or-9-monitor\/\" title=\"Director\u2019s Monitor Cage for 7\u201dor 9\u201d Monitor\">\n            <div class=\"card-thumbnail\">\n                <img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/09\/porkeys-hd-1-cage-1-300x300.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/09\/porkeys-hd-1-cage-1-300x300.jpg 300w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/09\/porkeys-hd-1-cage-1-150x150.jpg 150w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/09\/porkeys-hd-1-cage-1-600x600.jpg 600w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/09\/porkeys-hd-1-cage-1.jpg 1000w\" sizes=\"300px\" \/>            <\/div>\n        <\/a>\n\n        <div class=\"product-tags\">\n            \n            \n            \n                    <\/div>\n    <\/div>\n    <div class=\"card-content\">\n                <div class=\"brand\">\n            <a class=\"brand-link\" href=\"https:\/\/mediatrade.fi\/en\/tuote-osasto\/all-products\/?brands=portkeys\">Portkeys<\/a>\n        <\/div>\n                <h3 class=\"h3 card-title\"><a class=\"product-card-link\" id=\"card-link-6a978ab08b99f\" href=\"https:\/\/mediatrade.fi\/en\/product\/directors-monitor-cage-for-7or-9-monitor\/\" rel=\"bookmark\">Director\u2019s Monitor Cage for 7\u201dor 9\u201d Monitor<\/a><\/h3>                    <div class=\"price\">\n                87&nbsp;&euro;<span class=\"tax\">(VAT 0%)<\/span>\n            <\/div>\n                    <\/div>\n<\/div>\n        <\/div>\n            <div class=\"slide\">\n            <div class=\"card product product-feature-tracking\" onclick=\"document.getElementById('card-link-6a978ab08c98f').click();\" data-product='{\"title\":\"Litepanels Lykos+ BiColor Flight Kit\",\"sku\":\"935-3191\",\"price\":\"2455\",\"brand_name\":\"Litepanels\",\"link\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/litepanels-lykos-bicolor-flight-kit-2\\\/\"}'>\n    <div class=\"thumbnail-wrap\">\n        <a href=\"https:\/\/mediatrade.fi\/en\/product\/litepanels-lykos-bicolor-flight-kit-2\/\" title=\"Litepanels Lykos+ BiColor Flight Kit\">\n            <div class=\"card-thumbnail\">\n                <img decoding=\"async\" width=\"300\" height=\"151\" src=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/manfrotto-lykosledlight-flightkitbylitepanels_2-300x151.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/manfrotto-lykosledlight-flightkitbylitepanels_2-300x151.jpg 300w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/manfrotto-lykosledlight-flightkitbylitepanels_2-1024x514.jpg 1024w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/manfrotto-lykosledlight-flightkitbylitepanels_2-768x386.jpg 768w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/manfrotto-lykosledlight-flightkitbylitepanels_2-600x301.jpg 600w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/manfrotto-lykosledlight-flightkitbylitepanels_2-597x300.jpg 597w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/manfrotto-lykosledlight-flightkitbylitepanels_2.jpg 1366w\" sizes=\"300px\" \/>            <\/div>\n        <\/a>\n\n        <div class=\"product-tags\">\n            \n            \n            \n                    <\/div>\n    <\/div>\n    <div class=\"card-content\">\n                <div class=\"brand\">\n            <a class=\"brand-link\" href=\"https:\/\/mediatrade.fi\/en\/tuote-osasto\/all-products\/?brands=litepanels\">Litepanels<\/a>\n        <\/div>\n                <h3 class=\"h3 card-title\"><a class=\"product-card-link\" id=\"card-link-6a978ab08c98f\" href=\"https:\/\/mediatrade.fi\/en\/product\/litepanels-lykos-bicolor-flight-kit-2\/\" rel=\"bookmark\">Litepanels Lykos+ BiColor Flight Kit<\/a><\/h3>                    <div class=\"price\">\n                2455&nbsp;&euro;<span class=\"tax\">(VAT 0%)<\/span>\n            <\/div>\n                    <\/div>\n<\/div>\n        <\/div>\n            <div class=\"slide\">\n            <div class=\"card product product-feature-tracking\" onclick=\"document.getElementById('card-link-6a978ab08d62f').click();\" data-product='{\"title\":\"Litepanels Lykos+ BiColor Flight Kit with Battery\",\"sku\":\"935-3194\",\"price\":\"2795\",\"brand_name\":\"Litepanels\",\"link\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/litepanels-lykos-bicolor-flight-kit-with-battery-2\\\/\"}'>\n    <div class=\"thumbnail-wrap\">\n        <a href=\"https:\/\/mediatrade.fi\/en\/product\/litepanels-lykos-bicolor-flight-kit-with-battery-2\/\" title=\"Litepanels Lykos+ BiColor Flight Kit with Battery\">\n            <div class=\"card-thumbnail\">\n                <img decoding=\"async\" width=\"297\" height=\"300\" src=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/manfrotto-lykosledlight-flightkitwbattery-bundle-297x300.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/manfrotto-lykosledlight-flightkitwbattery-bundle-297x300.jpg 297w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/manfrotto-lykosledlight-flightkitwbattery-bundle-1012x1024.jpg 1012w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/manfrotto-lykosledlight-flightkitwbattery-bundle-768x777.jpg 768w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/manfrotto-lykosledlight-flightkitwbattery-bundle-600x607.jpg 600w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/manfrotto-lykosledlight-flightkitwbattery-bundle-100x100.jpg 100w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/manfrotto-lykosledlight-flightkitwbattery-bundle.jpg 1449w\" sizes=\"297px\" \/>            <\/div>\n        <\/a>\n\n        <div class=\"product-tags\">\n            \n            \n            \n                    <\/div>\n    <\/div>\n    <div class=\"card-content\">\n                <div class=\"brand\">\n            <a class=\"brand-link\" href=\"https:\/\/mediatrade.fi\/en\/tuote-osasto\/all-products\/?brands=litepanels\">Litepanels<\/a>\n        <\/div>\n                <h3 class=\"h3 card-title\"><a class=\"product-card-link\" id=\"card-link-6a978ab08d62f\" href=\"https:\/\/mediatrade.fi\/en\/product\/litepanels-lykos-bicolor-flight-kit-with-battery-2\/\" rel=\"bookmark\">Litepanels Lykos+ BiColor Flight Kit with Battery<\/a><\/h3>                    <div class=\"price\">\n                2795&nbsp;&euro;<span class=\"tax\">(VAT 0%)<\/span>\n            <\/div>\n                    <\/div>\n<\/div>\n        <\/div>\n            <div class=\"slide\">\n            <div class=\"card product product-feature-tracking\" onclick=\"document.getElementById('card-link-6a978ab08e2ba').click();\" data-product='{\"title\":\"1535 DigiCase Pro with Case Organizer\",\"sku\":\"INOV-DCP-1535\",\"price\":\"695\",\"brand_name\":\"Inovativ\",\"link\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/1535-digicase-pro-with-case-organizer-2\\\/\"}'>\n    <div class=\"thumbnail-wrap\">\n        <a href=\"https:\/\/mediatrade.fi\/en\/product\/1535-digicase-pro-with-case-organizer-2\/\" title=\"1535 DigiCase Pro with Case Organizer\">\n            <div class=\"card-thumbnail\">\n                <img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/inovativ-1535digicasepro-300x300.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/inovativ-1535digicasepro-300x300.jpg 300w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/inovativ-1535digicasepro-150x150.jpg 150w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/inovativ-1535digicasepro-600x600.jpg 600w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/inovativ-1535digicasepro.jpg 800w\" sizes=\"300px\" \/>            <\/div>\n        <\/a>\n\n        <div class=\"product-tags\">\n            \n            \n            \n                    <\/div>\n    <\/div>\n    <div class=\"card-content\">\n                <div class=\"brand\">\n            <a class=\"brand-link\" href=\"https:\/\/mediatrade.fi\/en\/tuote-osasto\/all-products\/?brands=inovativ\">Inovativ<\/a>\n        <\/div>\n                <h3 class=\"h3 card-title\"><a class=\"product-card-link\" id=\"card-link-6a978ab08e2ba\" href=\"https:\/\/mediatrade.fi\/en\/product\/1535-digicase-pro-with-case-organizer-2\/\" rel=\"bookmark\">1535 DigiCase Pro with Case Organizer<\/a><\/h3>                    <div class=\"price\">\n                695&nbsp;&euro;<span class=\"tax\">(VAT 0%)<\/span>\n            <\/div>\n                    <\/div>\n<\/div>\n        <\/div>\n            <div class=\"slide\">\n            <div class=\"card product product-feature-tracking\" onclick=\"document.getElementById('card-link-6a978ab08ef86').click();\" data-product='{\"title\":\"OR-46 &#8211; 3\\\/8 MALE TOP FOR OR-45\",\"sku\":\"OR-46\",\"price\":\"5\",\"brand_name\":\"Orca Bags\",\"link\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/or-46-3-8-male-top-for-or-45-2\\\/\"}'>\n    <div class=\"thumbnail-wrap\">\n        <a href=\"https:\/\/mediatrade.fi\/en\/product\/or-46-3-8-male-top-for-or-45-2\/\" title=\"OR-46 &#8211; 3\/8 MALE TOP FOR OR-45\">\n            <div class=\"card-thumbnail\">\n                <img decoding=\"async\" width=\"300\" height=\"275\" src=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/06\/OR-46-300x275.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/06\/OR-46-300x275.jpg 300w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/06\/OR-46-327x300.jpg 327w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2023\/06\/OR-46.jpg 600w\" sizes=\"300px\" \/>            <\/div>\n        <\/a>\n\n        <div class=\"product-tags\">\n            \n            \n            \n                            <div class=\"product-tag limited\">Outlet<\/div>\n                    <\/div>\n    <\/div>\n    <div class=\"card-content\">\n                <div class=\"brand\">\n            <a class=\"brand-link\" href=\"https:\/\/mediatrade.fi\/en\/tuote-osasto\/all-products\/?brands=orca-bags\">Orca Bags<\/a>\n        <\/div>\n                <h3 class=\"h3 card-title\"><a class=\"product-card-link\" id=\"card-link-6a978ab08ef86\" href=\"https:\/\/mediatrade.fi\/en\/product\/or-46-3-8-male-top-for-or-45-2\/\" rel=\"bookmark\">OR-46 &#8211; 3\/8 MALE TOP FOR OR-45<\/a><\/h3>                    <div class=\"price\">\n                5&nbsp;&euro;<span class=\"tax\">(VAT 0%)<\/span>\n            <\/div>\n                    <\/div>\n<\/div>\n        <\/div>\n        <\/div>            <\/div>\n        <\/div>\n            <\/div>\n<\/section>\n\n\n\n<section class=\"block block-profile-listing container-fluid \">\n    <div class=\"container\">\n        <div class=\"row\">\n            <main class=\"entry-content col-12\">\n                \n\n<h2 class=\"wp-block-heading\">Asiantuntijamme<\/h2>\n\n\n            <\/main>\n                        <div class=\"col-12 col-lg-6\">\n                <div class=\"person-wrapper\">\n                    <div class=\"image-wrapper\">\n                        <img decoding=\"async\" width=\"1920\" height=\"3414\" src=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/Kaposempi-mr.-Tommi-Rosnell-1920x3414.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/Kaposempi-mr.-Tommi-Rosnell-1920x3414.jpg 1920w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/Kaposempi-mr.-Tommi-Rosnell-169x300.jpg 169w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/Kaposempi-mr.-Tommi-Rosnell-576x1024.jpg 576w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/Kaposempi-mr.-Tommi-Rosnell-768x1365.jpg 768w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/Kaposempi-mr.-Tommi-Rosnell-864x1536.jpg 864w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/Kaposempi-mr.-Tommi-Rosnell-1152x2048.jpg 1152w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/Kaposempi-mr.-Tommi-Rosnell-600x1067.jpg 600w, https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/Kaposempi-mr.-Tommi-Rosnell-scaled.jpg 1440w\" sizes=\"(max-width: 575px) 100vw, (max-width: 767px) 570, (max-width: 991px) 830, (max-width: 1199px) 930, 994px\" \/>                    <\/div>\n                    <div class=\"content-wrapper\">\n                        <h4 class=\"name\">Tommi Rosnell<\/h4>\n                        <p class=\"title\">Business Development Manager<\/p>\n                        <p class=\"summary\">I work as a production lighting specialist at Mediatrade. My expertise lies in designing studio lighting and planning production workflows.<\/p>\n                                                <span class=\"knowledge-title\">Area of expertise<\/span>\n                        <p class=\"knowledge\">Post-production, cinematography, lighting<\/p>\n                                                <p class=\"phone\">+358201557730<\/p>\n                        <p class=\"email\">tommi.rosnell@mediatrade.fi<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                                <\/div>\n    <\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":38978,"template":"","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"57311,96105,56952,56959,62429,124742","_relevanssi_noindex_reason":""},"product_brand":[],"product_cat":[2486,3510,212,9057,15,3509,43,8189],"product_tag":[1463,3864,3865,1389,1386,838,2490],"brands":[680],"id_product_type":[],"class_list":["post-398985","product","type-product","status-publish","has-post-thumbnail","product_cat-all-products","product_cat-cine-and-studio-ligthing","product_cat-cine-ja-studiovalaisu-tarvikkeet","product_cat-in-store","product_cat-kaikki","product_cat-light-en","product_cat-valo","product_cat-varastossa","product_tag-astra","product_tag-carry-case","product_tag-case-for-astra-or-gemini","product_tag-gemini","product_tag-litepanels","product_tag-mediatrade","product_tag-mediatrade-en","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":2,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Light carry case for (1) Astra or (1) Gemini 1x1 - Mediatrade<\/title>\n<meta name=\"description\" content=\"Comfortably and securely transport one Astra or Gemini 1x1 fixture with yoke, power supply and gels.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mediatrade.fi\/en\/product\/light-carry-case-for-1-astra-or-1-gemini-1x1-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Light carry case for (1) Astra or (1) Gemini 1x1 - Mediatrade\" \/>\n<meta property=\"og:description\" content=\"Comfortably and securely transport one Astra or Gemini 1x1 fixture with yoke, power supply and gels.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mediatrade.fi\/en\/product\/light-carry-case-for-1-astra-or-1-gemini-1x1-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Mediatrade\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-19T17:15:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/litepanels-lightcarrycasefor1astra1x1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1256\" \/>\n\t<meta property=\"og:image:height\" content=\"1884\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/light-carry-case-for-1-astra-or-1-gemini-1x1-2\\\/\",\"url\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/light-carry-case-for-1-astra-or-1-gemini-1x1-2\\\/\",\"name\":\"Light carry case for (1) Astra or (1) Gemini 1x1 - Mediatrade\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/light-carry-case-for-1-astra-or-1-gemini-1x1-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/light-carry-case-for-1-astra-or-1-gemini-1x1-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mediatrade.fi\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/litepanels-lightcarrycasefor1astra1x1.jpg\",\"datePublished\":\"2025-01-21T21:40:50+00:00\",\"dateModified\":\"2026-03-19T17:15:07+00:00\",\"description\":\"Comfortably and securely transport one Astra or Gemini 1x1 fixture with yoke, power supply and gels.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/light-carry-case-for-1-astra-or-1-gemini-1x1-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/light-carry-case-for-1-astra-or-1-gemini-1x1-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/light-carry-case-for-1-astra-or-1-gemini-1x1-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mediatrade.fi\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/litepanels-lightcarrycasefor1astra1x1.jpg\",\"contentUrl\":\"https:\\\/\\\/mediatrade.fi\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/litepanels-lightcarrycasefor1astra1x1.jpg\",\"width\":1256,\"height\":1884},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/product\\\/light-carry-case-for-1-astra-or-1-gemini-1x1-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Etusivu\",\"item\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Light carry case for (1) Astra or (1) Gemini 1&#215;1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/\",\"name\":\"Mediatrade\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/#organization\",\"name\":\"Mediatrade\",\"url\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mediatrade.fi\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Group-640.svg\",\"contentUrl\":\"https:\\\/\\\/mediatrade.fi\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Group-640.svg\",\"width\":128,\"height\":43,\"caption\":\"Mediatrade\"},\"image\":{\"@id\":\"https:\\\/\\\/mediatrade.fi\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Light carry case for (1) Astra or (1) Gemini 1x1 - Mediatrade","description":"Comfortably and securely transport one Astra or Gemini 1x1 fixture with yoke, power supply and gels.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mediatrade.fi\/en\/product\/light-carry-case-for-1-astra-or-1-gemini-1x1-2\/","og_locale":"en_US","og_type":"article","og_title":"Light carry case for (1) Astra or (1) Gemini 1x1 - Mediatrade","og_description":"Comfortably and securely transport one Astra or Gemini 1x1 fixture with yoke, power supply and gels.","og_url":"https:\/\/mediatrade.fi\/en\/product\/light-carry-case-for-1-astra-or-1-gemini-1x1-2\/","og_site_name":"Mediatrade","article_modified_time":"2026-03-19T17:15:07+00:00","og_image":[{"width":1256,"height":1884,"url":"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/litepanels-lightcarrycasefor1astra1x1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mediatrade.fi\/en\/product\/light-carry-case-for-1-astra-or-1-gemini-1x1-2\/","url":"https:\/\/mediatrade.fi\/en\/product\/light-carry-case-for-1-astra-or-1-gemini-1x1-2\/","name":"Light carry case for (1) Astra or (1) Gemini 1x1 - Mediatrade","isPartOf":{"@id":"https:\/\/mediatrade.fi\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mediatrade.fi\/en\/product\/light-carry-case-for-1-astra-or-1-gemini-1x1-2\/#primaryimage"},"image":{"@id":"https:\/\/mediatrade.fi\/en\/product\/light-carry-case-for-1-astra-or-1-gemini-1x1-2\/#primaryimage"},"thumbnailUrl":"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/litepanels-lightcarrycasefor1astra1x1.jpg","datePublished":"2025-01-21T21:40:50+00:00","dateModified":"2026-03-19T17:15:07+00:00","description":"Comfortably and securely transport one Astra or Gemini 1x1 fixture with yoke, power supply and gels.","breadcrumb":{"@id":"https:\/\/mediatrade.fi\/en\/product\/light-carry-case-for-1-astra-or-1-gemini-1x1-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mediatrade.fi\/en\/product\/light-carry-case-for-1-astra-or-1-gemini-1x1-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mediatrade.fi\/en\/product\/light-carry-case-for-1-astra-or-1-gemini-1x1-2\/#primaryimage","url":"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/litepanels-lightcarrycasefor1astra1x1.jpg","contentUrl":"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/litepanels-lightcarrycasefor1astra1x1.jpg","width":1256,"height":1884},{"@type":"BreadcrumbList","@id":"https:\/\/mediatrade.fi\/en\/product\/light-carry-case-for-1-astra-or-1-gemini-1x1-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Etusivu","item":"https:\/\/mediatrade.fi\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/mediatrade.fi\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Light carry case for (1) Astra or (1) Gemini 1&#215;1"}]},{"@type":"WebSite","@id":"https:\/\/mediatrade.fi\/en\/#website","url":"https:\/\/mediatrade.fi\/en\/","name":"Mediatrade","description":"","publisher":{"@id":"https:\/\/mediatrade.fi\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mediatrade.fi\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mediatrade.fi\/en\/#organization","name":"Mediatrade","url":"https:\/\/mediatrade.fi\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mediatrade.fi\/en\/#\/schema\/logo\/image\/","url":"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/Group-640.svg","contentUrl":"https:\/\/mediatrade.fi\/wp-content\/uploads\/2022\/04\/Group-640.svg","width":128,"height":43,"caption":"Mediatrade"},"image":{"@id":"https:\/\/mediatrade.fi\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mediatrade.fi\/en\/wp-json\/wp\/v2\/product\/398985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mediatrade.fi\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mediatrade.fi\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mediatrade.fi\/en\/wp-json\/wp\/v2\/media\/38978"}],"wp:attachment":[{"href":"https:\/\/mediatrade.fi\/en\/wp-json\/wp\/v2\/media?parent=398985"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mediatrade.fi\/en\/wp-json\/wp\/v2\/product_brand?post=398985"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mediatrade.fi\/en\/wp-json\/wp\/v2\/product_cat?post=398985"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mediatrade.fi\/en\/wp-json\/wp\/v2\/product_tag?post=398985"},{"taxonomy":"brands","embeddable":true,"href":"https:\/\/mediatrade.fi\/en\/wp-json\/wp\/v2\/brands?post=398985"},{"taxonomy":"id_product_type","embeddable":true,"href":"https:\/\/mediatrade.fi\/en\/wp-json\/wp\/v2\/id_product_type?post=398985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}